{"id":42064,"date":"2015-04-20T13:10:02","date_gmt":"2015-04-20T13:10:02","guid":{"rendered":"https:\/\/nueva.perlaholidays.com\/?page_id=42064"},"modified":"2026-05-29T08:14:21","modified_gmt":"2026-05-29T08:14:21","slug":"lista-del-blog","status":"publish","type":"page","link":"https:\/\/perlaholidays.com\/es\/lista-del-blog\/","title":{"rendered":"Lista del blog"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El origen de la palabra \u00abviaje\u00bb probablemente se ha perdido en la historia. El t\u00e9rmino \u00abviaje\u00bb podr\u00eda tener su origen en la palabra del franc\u00e9s antiguo \u00abtravail\u00bb.[3] Seg\u00fan el diccionario Merriam Webster, el primer uso conocido de la palabra \u00abtravel\u00bb fue en el siglo XIV. Tambi\u00e9n afirma que la palabra proviene del ingl\u00e9s medio \u00abtravailen\u00bb, \u00abtravelen\u00bb (que significa atormentar, trabajar, esforzarse, viajar) y, anteriormente, del franc\u00e9s antiguo \u00abtravailler\u00bb (que significa trabajar arduamente, afanarse).   <\/p>\n\n<p class=\"wp-block-paragraph\">En ingl\u00e9s, todav\u00eda usamos ocasionalmente las palabras \u00abtravail\u00bb y \u00abtravails\u00bb, que significan lucha. Seg\u00fan Simon Winchester en su libro The Best Travelers&#8217; Tales (2004), las palabras \u00abtravel\u00bb y \u00abtravail\u00bb comparten una ra\u00edz a\u00fan m\u00e1s antigua: un instrumento de tortura romano llamado tripalium (en lat\u00edn significa \u00abtres estacas\u00bb, como en empalar). Este v\u00ednculo refleja la extrema dificultad de viajar en la antig\u00fcedad.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El origen de la palabra \u00abviaje\u00bb probablemente se ha perdido en la historia. El t\u00e9rmino \u00abviaje\u00bb podr\u00eda tener su origen en la palabra del franc\u00e9s antiguo \u00abtravail\u00bb.[3] Seg\u00fan el diccionario Merriam Webster, el primer uso conocido de la palabra \u00abtravel\u00bb fue en el siglo XIV. Tambi\u00e9n afirma que la palabra proviene del ingl\u00e9s medio \u00abtravailen\u00bb, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"blog_list.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-42064","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lista del blog - Perla Holidays<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lista del blog - Perla Holidays\" \/>\n<meta property=\"og:description\" content=\"El origen de la palabra \u00abviaje\u00bb probablemente se ha perdido en la historia. El t\u00e9rmino \u00abviaje\u00bb podr\u00eda tener su origen en la palabra del franc\u00e9s antiguo \u00abtravail\u00bb.[3] Seg\u00fan el diccionario Merriam Webster, el primer uso conocido de la palabra \u00abtravel\u00bb fue en el siglo XIV. Tambi\u00e9n afirma que la palabra proviene del ingl\u00e9s medio \u00abtravailen\u00bb, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlaholidays.com\/blog-list\/\" \/>\n<meta property=\"og:site_name\" content=\"Perla Holidays\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T08:14:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/blog-list\\\/\",\"url\":\"https:\\\/\\\/perlaholidays.com\\\/blog-list\\\/\",\"name\":\"Lista del blog - Perla Holidays\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/#website\"},\"datePublished\":\"2015-04-20T13:10:02+00:00\",\"dateModified\":\"2026-05-29T08:14:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/blog-list\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlaholidays.com\\\/blog-list\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/blog-list\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlaholidays.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lista del blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/#website\",\"url\":\"https:\\\/\\\/perlaholidays.com\\\/\",\"name\":\"Perla Holidays\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlaholidays.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/#organization\",\"name\":\"Perla Holidays\",\"url\":\"https:\\\/\\\/perlaholidays.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlaholidays.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo.webp\",\"contentUrl\":\"https:\\\/\\\/perlaholidays.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo.webp\",\"width\":656,\"height\":265,\"caption\":\"Perla Holidays\"},\"image\":{\"@id\":\"https:\\\/\\\/perlaholidays.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lista del blog - Perla Holidays","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Lista del blog - Perla Holidays","og_description":"El origen de la palabra \u00abviaje\u00bb probablemente se ha perdido en la historia. El t\u00e9rmino \u00abviaje\u00bb podr\u00eda tener su origen en la palabra del franc\u00e9s antiguo \u00abtravail\u00bb.[3] Seg\u00fan el diccionario Merriam Webster, el primer uso conocido de la palabra \u00abtravel\u00bb fue en el siglo XIV. Tambi\u00e9n afirma que la palabra proviene del ingl\u00e9s medio \u00abtravailen\u00bb, ...","og_url":"https:\/\/perlaholidays.com\/blog-list\/","og_site_name":"Perla Holidays","article_modified_time":"2026-05-29T08:14:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/perlaholidays.com\/blog-list\/","url":"https:\/\/perlaholidays.com\/blog-list\/","name":"Lista del blog - Perla Holidays","isPartOf":{"@id":"https:\/\/perlaholidays.com\/#website"},"datePublished":"2015-04-20T13:10:02+00:00","dateModified":"2026-05-29T08:14:21+00:00","breadcrumb":{"@id":"https:\/\/perlaholidays.com\/blog-list\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlaholidays.com\/blog-list\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/perlaholidays.com\/blog-list\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlaholidays.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lista del blog"}]},{"@type":"WebSite","@id":"https:\/\/perlaholidays.com\/#website","url":"https:\/\/perlaholidays.com\/","name":"Perla Holidays","description":"","publisher":{"@id":"https:\/\/perlaholidays.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlaholidays.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/perlaholidays.com\/#organization","name":"Perla Holidays","url":"https:\/\/perlaholidays.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/perlaholidays.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlaholidays.com\/wp-content\/uploads\/2026\/05\/logo.webp","contentUrl":"https:\/\/perlaholidays.com\/wp-content\/uploads\/2026\/05\/logo.webp","width":656,"height":265,"caption":"Perla Holidays"},"image":{"@id":"https:\/\/perlaholidays.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/pages\/42064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/comments?post=42064"}],"version-history":[{"count":1,"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/pages\/42064\/revisions"}],"predecessor-version":[{"id":42065,"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/pages\/42064\/revisions\/42065"}],"wp:attachment":[{"href":"https:\/\/perlaholidays.com\/es\/wp-json\/wp\/v2\/media?parent=42064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}